{"id":2619,"date":"2023-11-26T12:15:27","date_gmt":"2023-11-26T15:15:27","guid":{"rendered":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/"},"modified":"2023-11-26T12:15:40","modified_gmt":"2023-11-26T15:15:40","slug":"safado-faz-sexo-com-as-novinhas-estudante","status":"publish","type":"post","link":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/","title":{"rendered":"Safado faz sexo com as novinhas estudante"},"content":{"rendered":"O safado esta fazendo um sexo com as <a href=\"https:\/\/xvideos.tv.br\/videos\/novinhas\/\">novinhas<\/a> estudante. Este macho soca cada vez mais a rola na puta gostosa que adora ter a piroca forte do rapaz sendo penetrada em si. Esta morena quente esta toda exitada na fodida boa que faz com este rapaz. E esta gostosa geme muito de prazer na foda que tem ali.","protected":false},"excerpt":{"rendered":"<p>O safado esta fazendo um sexo com as novinhas estudante. Este macho soca cada vez mais a rola na puta gostosa que adora ter a piroca forte do rapaz sendo penetrada em si. Esta morena quente esta toda exitada na fodida boa que faz com este rapaz. E esta gostosa geme muito de prazer na foda que tem ali.<\/p>\n","protected":false},"author":4,"featured_media":2620,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[14],"tags":[792,458,386,23],"class_list":["post-2619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caiu-na-net","tag-estudante","tag-novinhas","tag-safado","tag-sexo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Safado Faz Sexo Com As Novinhas Estudante - Xvideos<\/title>\n<meta name=\"description\" content=\"O safado esta fazendo um sexo com as novinhas estudante. Este macho soca cada vez mais a rola na puta gostosa que adora ter a piroca forte do rapaz sendo pe\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Safado faz sexo com as novinhas estudante - Xvideos\" \/>\n<meta property=\"og:description\" content=\"O safado esta fazendo um sexo com as novinhas estudante. Este macho soca cada vez mais a rola na puta gostosa que adora ter a piroca forte do rapaz sendo pe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/\" \/>\n<meta property=\"og:site_name\" content=\"Xvideos \u2192 Xvideo Brasil = X Videos Amador\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-26T15:15:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-26T15:15:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xvideos.tv.br\/wp-content\/uploads\/2017\/05\/safado-faz-sexo-com-as-novinhas-estudante.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"488\" \/>\n\t<meta property=\"og:image:height\" content=\"366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"willian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"willian\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/\"},\"author\":{\"name\":\"willian\",\"@id\":\"https:\/\/xvideos.tv.br\/#\/schema\/person\/c756f52a2ef4ca13d343696af280ea06\"},\"headline\":\"Safado faz sexo com as novinhas estudante\",\"datePublished\":\"2023-11-26T15:15:27+00:00\",\"dateModified\":\"2023-11-26T15:15:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/\"},\"wordCount\":66,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/xvideos.tv.br\/#\/schema\/person\/354a9cd9ee5223ec31188d15147faeae\"},\"image\":{\"@id\":\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xvideos.tv.br\/wp-content\/uploads\/2017\/05\/safado-faz-sexo-com-as-novinhas-estudante.jpg\",\"keywords\":[\"estudante\",\"novinhas\",\"safado\",\"sexo\"],\"articleSection\":[\"Caiu na Net\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/\",\"url\":\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/\",\"name\":\"Safado faz sexo com as novinhas estudante - Xvideos\",\"isPartOf\":{\"@id\":\"https:\/\/xvideos.tv.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xvideos.tv.br\/wp-content\/uploads\/2017\/05\/safado-faz-sexo-com-as-novinhas-estudante.jpg\",\"datePublished\":\"2023-11-26T15:15:27+00:00\",\"dateModified\":\"2023-11-26T15:15:40+00:00\",\"description\":\"O safado esta fazendo um sexo com as novinhas estudante. Este macho soca cada vez mais a rola na puta gostosa que adora ter a piroca forte do rapaz sendo pe\",\"breadcrumb\":{\"@id\":\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#primaryimage\",\"url\":\"https:\/\/xvideos.tv.br\/wp-content\/uploads\/2017\/05\/safado-faz-sexo-com-as-novinhas-estudante.jpg\",\"contentUrl\":\"https:\/\/xvideos.tv.br\/wp-content\/uploads\/2017\/05\/safado-faz-sexo-com-as-novinhas-estudante.jpg\",\"width\":488,\"height\":366,\"caption\":\"Safado faz sexo com as novinhas estudante\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Xvideos\",\"item\":\"https:\/\/xvideos.tv.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caiu na Net\",\"item\":\"https:\/\/xvideos.tv.br\/videos\/caiu-na-net\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Safado faz sexo com as novinhas estudante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xvideos.tv.br\/#website\",\"url\":\"https:\/\/xvideos.tv.br\/\",\"name\":\"Xvideos \u2192 Xvideo Brasil = X Videos Amador\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/xvideos.tv.br\/#\/schema\/person\/354a9cd9ee5223ec31188d15147faeae\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xvideos.tv.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/xvideos.tv.br\/#\/schema\/person\/354a9cd9ee5223ec31188d15147faeae\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/xvideos.tv.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/579d487f4a89cc1bfc616df387c41b13c1131d82a352a3348433a051ceaabd9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/579d487f4a89cc1bfc616df387c41b13c1131d82a352a3348433a051ceaabd9d?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/xvideos.tv.br\/#\/schema\/person\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/xvideos.tv.br\/#\/schema\/person\/c756f52a2ef4ca13d343696af280ea06\",\"name\":\"willian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/xvideos.tv.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f34af5784683be9409fd9856466a4d47be66288b4bf0343089acb8d39a5fa7e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f34af5784683be9409fd9856466a4d47be66288b4bf0343089acb8d39a5fa7e6?s=96&d=mm&r=g\",\"caption\":\"willian\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Safado Faz Sexo Com As Novinhas Estudante - Xvideos","description":"O safado esta fazendo um sexo com as novinhas estudante. Este macho soca cada vez mais a rola na puta gostosa que adora ter a piroca forte do rapaz sendo pe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/","og_locale":"pt_BR","og_type":"article","og_title":"Safado faz sexo com as novinhas estudante - Xvideos","og_description":"O safado esta fazendo um sexo com as novinhas estudante. Este macho soca cada vez mais a rola na puta gostosa que adora ter a piroca forte do rapaz sendo pe","og_url":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/","og_site_name":"Xvideos \u2192 Xvideo Brasil = X Videos Amador","article_published_time":"2023-11-26T15:15:27+00:00","article_modified_time":"2023-11-26T15:15:40+00:00","og_image":[{"width":488,"height":366,"url":"https:\/\/xvideos.tv.br\/wp-content\/uploads\/2017\/05\/safado-faz-sexo-com-as-novinhas-estudante.jpg","type":"image\/jpeg"}],"author":"willian","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"willian"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#article","isPartOf":{"@id":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/"},"author":{"name":"willian","@id":"https:\/\/xvideos.tv.br\/#\/schema\/person\/c756f52a2ef4ca13d343696af280ea06"},"headline":"Safado faz sexo com as novinhas estudante","datePublished":"2023-11-26T15:15:27+00:00","dateModified":"2023-11-26T15:15:40+00:00","mainEntityOfPage":{"@id":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/"},"wordCount":66,"commentCount":0,"publisher":{"@id":"https:\/\/xvideos.tv.br\/#\/schema\/person\/354a9cd9ee5223ec31188d15147faeae"},"image":{"@id":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#primaryimage"},"thumbnailUrl":"https:\/\/xvideos.tv.br\/wp-content\/uploads\/2017\/05\/safado-faz-sexo-com-as-novinhas-estudante.jpg","keywords":["estudante","novinhas","safado","sexo"],"articleSection":["Caiu na Net"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/","url":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/","name":"Safado faz sexo com as novinhas estudante - Xvideos","isPartOf":{"@id":"https:\/\/xvideos.tv.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#primaryimage"},"image":{"@id":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#primaryimage"},"thumbnailUrl":"https:\/\/xvideos.tv.br\/wp-content\/uploads\/2017\/05\/safado-faz-sexo-com-as-novinhas-estudante.jpg","datePublished":"2023-11-26T15:15:27+00:00","dateModified":"2023-11-26T15:15:40+00:00","description":"O safado esta fazendo um sexo com as novinhas estudante. Este macho soca cada vez mais a rola na puta gostosa que adora ter a piroca forte do rapaz sendo pe","breadcrumb":{"@id":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#primaryimage","url":"https:\/\/xvideos.tv.br\/wp-content\/uploads\/2017\/05\/safado-faz-sexo-com-as-novinhas-estudante.jpg","contentUrl":"https:\/\/xvideos.tv.br\/wp-content\/uploads\/2017\/05\/safado-faz-sexo-com-as-novinhas-estudante.jpg","width":488,"height":366,"caption":"Safado faz sexo com as novinhas estudante"},{"@type":"BreadcrumbList","@id":"https:\/\/xvideos.tv.br\/caiu-na-net\/safado-faz-sexo-com-as-novinhas-estudante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Xvideos","item":"https:\/\/xvideos.tv.br\/"},{"@type":"ListItem","position":2,"name":"Caiu na Net","item":"https:\/\/xvideos.tv.br\/videos\/caiu-na-net\/"},{"@type":"ListItem","position":3,"name":"Safado faz sexo com as novinhas estudante"}]},{"@type":"WebSite","@id":"https:\/\/xvideos.tv.br\/#website","url":"https:\/\/xvideos.tv.br\/","name":"Xvideos \u2192 Xvideo Brasil = X Videos Amador","description":"","publisher":{"@id":"https:\/\/xvideos.tv.br\/#\/schema\/person\/354a9cd9ee5223ec31188d15147faeae"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xvideos.tv.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/xvideos.tv.br\/#\/schema\/person\/354a9cd9ee5223ec31188d15147faeae","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/xvideos.tv.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/579d487f4a89cc1bfc616df387c41b13c1131d82a352a3348433a051ceaabd9d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/579d487f4a89cc1bfc616df387c41b13c1131d82a352a3348433a051ceaabd9d?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/xvideos.tv.br\/#\/schema\/person\/image\/"}},{"@type":"Person","@id":"https:\/\/xvideos.tv.br\/#\/schema\/person\/c756f52a2ef4ca13d343696af280ea06","name":"willian","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/xvideos.tv.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f34af5784683be9409fd9856466a4d47be66288b4bf0343089acb8d39a5fa7e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f34af5784683be9409fd9856466a4d47be66288b4bf0343089acb8d39a5fa7e6?s=96&d=mm&r=g","caption":"willian"}}]}},"views":69631,"_links":{"self":[{"href":"https:\/\/xvideos.tv.br\/wp-json\/wp\/v2\/posts\/2619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xvideos.tv.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xvideos.tv.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xvideos.tv.br\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/xvideos.tv.br\/wp-json\/wp\/v2\/comments?post=2619"}],"version-history":[{"count":0,"href":"https:\/\/xvideos.tv.br\/wp-json\/wp\/v2\/posts\/2619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xvideos.tv.br\/wp-json\/wp\/v2\/media\/2620"}],"wp:attachment":[{"href":"https:\/\/xvideos.tv.br\/wp-json\/wp\/v2\/media?parent=2619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xvideos.tv.br\/wp-json\/wp\/v2\/categories?post=2619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xvideos.tv.br\/wp-json\/wp\/v2\/tags?post=2619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}